{"id":76094,"date":"2026-09-01T13:05:49","date_gmt":"2026-09-01T11:05:49","guid":{"rendered":"https:\/\/art-manikure.de\/?post_type=product&#038;p=76094"},"modified":"2026-09-01T14:06:31","modified_gmt":"2026-09-01T12:06:31","slug":"joia-gel-nail-polish-vegan-186","status":"publish","type":"product","link":"https:\/\/art-manikure.de\/en\/shop\/gel-polishes\/gel-polish-en\/joia-gel-nail-polish-vegan-186\/","title":{"rendered":"JOIA Gel Nail Polish Vegan 186"},"content":{"rendered":"<ul>\n<li>Gellack mit selbstgl\u00e4ttender Beschichtung, bildet keine Unebenheiten<\/li>\n<li>Die bequemste Anwendung, dank eines hochwertigen Pinsels<\/li>\n<li>Perfektes Auftragen in einer einzigen Schicht. Verteilt sich nicht und zieht keine Streifen<\/li>\n<li>Unglaubliche Haltbarkeit, Dichte, Helligkeit, S\u00e4ttigung des Pigments<\/li>\n<li>Schnelle Polymerisation<\/li>\n<li>Hat keinen starken Geruch<\/li>\n<li>Die einzigartige 15 FREE Formel<\/li>\n<\/ul>\n<p><strong>Wie zu verwenden:<\/strong><\/p>\n<ol>\n<li>Entfernen Sie den Glanz von der gesamten Oberfl\u00e4che des Nagels mit einem Schwabbel mit 180er K\u00f6rnung oder einer Feile mit 240er K\u00f6rnung, \u00fcberziehen Sie ihn mit dem Nail Dryer JOIA vegan und dem s\u00e4urefreien Nail Primer JOIA vegan.<\/li>\n<li>Eine d\u00fcnne Schicht Unterlack auftragen und aush\u00e4rten lassen.<\/li>\n<li>Gellack auftragen und in einer 48 W LED-Lampe f\u00fcr mindestens 60 Sekunden aush\u00e4rten. Falls erforderlich, kann der Vorgang nach der Polymerisation der ersten Schicht wiederholt werden.<\/li>\n<li>JOIA vegan matt oder gl\u00e4nzend auftragen und mindestens 60 Sekunden lang in einer 48-W-LED-Lampe aush\u00e4rten.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Gellack mit selbstgl\u00e4ttender Beschichtung, bildet keine Unebenheiten Die bequemste Anwendung, dank eines hochwertigen Pinsels Perfektes Auftragen in einer einzigen Schicht.<\/p>\n","protected":false},"featured_media":76116,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1126,1277],"product_tag":[2453],"class_list":["post-76094","product","type-product","status-publish","has-post-thumbnail","product_cat-gel-lacke","product_cat-gel-polish","product_tag-gellack","first","instock","taxable","shipping-taxable","purchasable","product-type-simple","has-product-safety-information"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>JOIA Gel Nail Polish Vegan 186 &#8226; Art-Manik\u00fcre<\/title>\n<meta name=\"description\" content=\"Gellack mit selbstgl\u00e4ttender Beschichtung, bildet keine UnebenheitenDie bequemste Anwendung, dank eines hochwertigen PinselsPerfektes Auftragen in einer einzigen Schicht. Verteilt sich nicht und zieht keine StreifenUnglaubliche Haltbarkeit, Dichte, Helligkeit, S\u00e4ttigung des PigmentsSchnelle PolymerisationHat keinen starken GeruchDie einzigartige 15 FREE Formel\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/art-manikure.de\/en\/shop\/gel-polishes\/gel-polish-en\/joia-gel-nail-polish-vegan-186\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JOIA Gel Nail Polish Vegan 186\" \/>\n<meta property=\"og:description\" content=\"Gellack mit selbstgl\u00e4ttender Beschichtung, bildet keine UnebenheitenDie bequemste Anwendung, dank eines hochwertigen PinselsPerfektes Auftragen in einer einzigen Schicht. Verteilt sich nicht und zieht keine StreifenUnglaubliche Haltbarkeit, Dichte, Helligkeit, S\u00e4ttigung des PigmentsSchnelle PolymerisationHat keinen starken GeruchDie einzigartige 15 FREE Formel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/art-manikure.de\/en\/shop\/gel-polishes\/gel-polish-en\/joia-gel-nail-polish-vegan-186\/\" \/>\n<meta property=\"og:site_name\" content=\"Art-Manik\u00fcre\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T12:06:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/art-manikure.de\/wp-content\/uploads\/2026\/09\/03186-500x500-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/art-manikure.de\\\/en\\\/shop\\\/gel-polishes\\\/gel-polish-en\\\/joia-gel-nail-polish-vegan-186\\\/\",\"url\":\"https:\\\/\\\/art-manikure.de\\\/en\\\/shop\\\/gel-polishes\\\/gel-polish-en\\\/joia-gel-nail-polish-vegan-186\\\/\",\"name\":\"JOIA Gel Nail Polish Vegan 186 &#8226; Art-Manik\u00fcre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/art-manikure.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/art-manikure.de\\\/en\\\/shop\\\/gel-polishes\\\/gel-polish-en\\\/joia-gel-nail-polish-vegan-186\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/art-manikure.de\\\/en\\\/shop\\\/gel-polishes\\\/gel-polish-en\\\/joia-gel-nail-polish-vegan-186\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/art-manikure.de\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/03186-500x500-1.webp\",\"datePublished\":\"2026-09-01T11:05:49+00:00\",\"dateModified\":\"2026-09-01T12:06:31+00:00\",\"description\":\"Gellack mit selbstgl\u00e4ttender Beschichtung, bildet keine UnebenheitenDie bequemste Anwendung, dank eines hochwertigen PinselsPerfektes Auftragen in einer einzigen Schicht. Verteilt sich nicht und zieht keine StreifenUnglaubliche Haltbarkeit, Dichte, Helligkeit, S\u00e4ttigung des PigmentsSchnelle PolymerisationHat keinen starken GeruchDie einzigartige 15 FREE Formel\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/art-manikure.de\\\/en\\\/shop\\\/gel-polishes\\\/gel-polish-en\\\/joia-gel-nail-polish-vegan-186\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/art-manikure.de\\\/en\\\/shop\\\/gel-polishes\\\/gel-polish-en\\\/joia-gel-nail-polish-vegan-186\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/art-manikure.de\\\/en\\\/shop\\\/gel-polishes\\\/gel-polish-en\\\/joia-gel-nail-polish-vegan-186\\\/#primaryimage\",\"url\":\"https:\\\/\\\/art-manikure.de\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/03186-500x500-1.webp\",\"contentUrl\":\"https:\\\/\\\/art-manikure.de\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/03186-500x500-1.webp\",\"width\":500,\"height\":500,\"caption\":\"JOIA Gel Nail Polish Vegan 186\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/art-manikure.de\\\/en\\\/shop\\\/gel-polishes\\\/gel-polish-en\\\/joia-gel-nail-polish-vegan-186\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/art-manikure.de\\\/en\\\/home-en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Store\",\"item\":\"https:\\\/\\\/www.art-manikure.de\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"JOIA Gel Nail Polish Vegan 186\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/art-manikure.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/art-manikure.de\\\/en\\\/\",\"name\":\"Art-Manik\u00fcre\",\"description\":\"Profi Werkzeuge &amp; Zubeh\u00f6r f\u00fcr Manik\u00fcre und SMART Pedik\u00fcre\",\"publisher\":{\"@id\":\"https:\\\/\\\/art-manikure.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/art-manikure.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/art-manikure.de\\\/en\\\/#organization\",\"name\":\"KIRA GmbH\",\"url\":\"https:\\\/\\\/art-manikure.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/art-manikure.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/art-manikure.de\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo-black-4.svg\",\"contentUrl\":\"https:\\\/\\\/art-manikure.de\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo-black-4.svg\",\"width\":200,\"height\":28,\"caption\":\"KIRA GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/art-manikure.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/art_manikure.de\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"JOIA Gel Nail Polish Vegan 186 &#8226; Art-Manik\u00fcre","description":"Gellack mit selbstgl\u00e4ttender Beschichtung, bildet keine UnebenheitenDie bequemste Anwendung, dank eines hochwertigen PinselsPerfektes Auftragen in einer einzigen Schicht. Verteilt sich nicht und zieht keine StreifenUnglaubliche Haltbarkeit, Dichte, Helligkeit, S\u00e4ttigung des PigmentsSchnelle PolymerisationHat keinen starken GeruchDie einzigartige 15 FREE Formel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/art-manikure.de\/en\/shop\/gel-polishes\/gel-polish-en\/joia-gel-nail-polish-vegan-186\/","og_locale":"en_US","og_type":"article","og_title":"JOIA Gel Nail Polish Vegan 186","og_description":"Gellack mit selbstgl\u00e4ttender Beschichtung, bildet keine UnebenheitenDie bequemste Anwendung, dank eines hochwertigen PinselsPerfektes Auftragen in einer einzigen Schicht. Verteilt sich nicht und zieht keine StreifenUnglaubliche Haltbarkeit, Dichte, Helligkeit, S\u00e4ttigung des PigmentsSchnelle PolymerisationHat keinen starken GeruchDie einzigartige 15 FREE Formel","og_url":"https:\/\/art-manikure.de\/en\/shop\/gel-polishes\/gel-polish-en\/joia-gel-nail-polish-vegan-186\/","og_site_name":"Art-Manik\u00fcre","article_modified_time":"2026-09-01T12:06:31+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/art-manikure.de\/wp-content\/uploads\/2026\/09\/03186-500x500-1.webp","type":"image\/webp"}],"twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/art-manikure.de\/en\/shop\/gel-polishes\/gel-polish-en\/joia-gel-nail-polish-vegan-186\/","url":"https:\/\/art-manikure.de\/en\/shop\/gel-polishes\/gel-polish-en\/joia-gel-nail-polish-vegan-186\/","name":"JOIA Gel Nail Polish Vegan 186 &#8226; Art-Manik\u00fcre","isPartOf":{"@id":"https:\/\/art-manikure.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/art-manikure.de\/en\/shop\/gel-polishes\/gel-polish-en\/joia-gel-nail-polish-vegan-186\/#primaryimage"},"image":{"@id":"https:\/\/art-manikure.de\/en\/shop\/gel-polishes\/gel-polish-en\/joia-gel-nail-polish-vegan-186\/#primaryimage"},"thumbnailUrl":"https:\/\/art-manikure.de\/wp-content\/uploads\/2026\/09\/03186-500x500-1.webp","datePublished":"2026-09-01T11:05:49+00:00","dateModified":"2026-09-01T12:06:31+00:00","description":"Gellack mit selbstgl\u00e4ttender Beschichtung, bildet keine UnebenheitenDie bequemste Anwendung, dank eines hochwertigen PinselsPerfektes Auftragen in einer einzigen Schicht. Verteilt sich nicht und zieht keine StreifenUnglaubliche Haltbarkeit, Dichte, Helligkeit, S\u00e4ttigung des PigmentsSchnelle PolymerisationHat keinen starken GeruchDie einzigartige 15 FREE Formel","breadcrumb":{"@id":"https:\/\/art-manikure.de\/en\/shop\/gel-polishes\/gel-polish-en\/joia-gel-nail-polish-vegan-186\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/art-manikure.de\/en\/shop\/gel-polishes\/gel-polish-en\/joia-gel-nail-polish-vegan-186\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/art-manikure.de\/en\/shop\/gel-polishes\/gel-polish-en\/joia-gel-nail-polish-vegan-186\/#primaryimage","url":"https:\/\/art-manikure.de\/wp-content\/uploads\/2026\/09\/03186-500x500-1.webp","contentUrl":"https:\/\/art-manikure.de\/wp-content\/uploads\/2026\/09\/03186-500x500-1.webp","width":500,"height":500,"caption":"JOIA Gel Nail Polish Vegan 186"},{"@type":"BreadcrumbList","@id":"https:\/\/art-manikure.de\/en\/shop\/gel-polishes\/gel-polish-en\/joia-gel-nail-polish-vegan-186\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/art-manikure.de\/en\/home-en\/"},{"@type":"ListItem","position":2,"name":"Store","item":"https:\/\/www.art-manikure.de\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"JOIA Gel Nail Polish Vegan 186"}]},{"@type":"WebSite","@id":"https:\/\/art-manikure.de\/en\/#website","url":"https:\/\/art-manikure.de\/en\/","name":"Art-Manik\u00fcre","description":"Profi Werkzeuge &amp; Zubeh\u00f6r f\u00fcr Manik\u00fcre und SMART Pedik\u00fcre","publisher":{"@id":"https:\/\/art-manikure.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/art-manikure.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/art-manikure.de\/en\/#organization","name":"KIRA GmbH","url":"https:\/\/art-manikure.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/art-manikure.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/art-manikure.de\/wp-content\/uploads\/2024\/01\/logo-black-4.svg","contentUrl":"https:\/\/art-manikure.de\/wp-content\/uploads\/2024\/01\/logo-black-4.svg","width":200,"height":28,"caption":"KIRA GmbH"},"image":{"@id":"https:\/\/art-manikure.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/art_manikure.de\/"]}]}},"_links":{"self":[{"href":"https:\/\/art-manikure.de\/en\/wp-json\/wp\/v2\/product\/76094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/art-manikure.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/art-manikure.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/art-manikure.de\/en\/wp-json\/wp\/v2\/comments?post=76094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/art-manikure.de\/en\/wp-json\/wp\/v2\/media\/76116"}],"wp:attachment":[{"href":"https:\/\/art-manikure.de\/en\/wp-json\/wp\/v2\/media?parent=76094"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/art-manikure.de\/en\/wp-json\/wp\/v2\/product_brand?post=76094"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/art-manikure.de\/en\/wp-json\/wp\/v2\/product_cat?post=76094"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/art-manikure.de\/en\/wp-json\/wp\/v2\/product_tag?post=76094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}